{"id":1146,"date":"2020-03-05T23:08:13","date_gmt":"2020-03-05T22:08:13","guid":{"rendered":"http:\/\/clubscience.etab.ac-lille.fr\/?p=1146"},"modified":"2020-03-05T23:08:13","modified_gmt":"2020-03-05T22:08:13","slug":"fabrication-de-nichoirs-et-dhotels-a-insectes","status":"publish","type":"post","link":"https:\/\/clubnaturepasteur.fr\/index.php\/2020\/03\/05\/fabrication-de-nichoirs-et-dhotels-a-insectes\/","title":{"rendered":"Fabrication de nichoirs et d\u2019h\u00f4tels \u00e0 insectes"},"content":{"rendered":"<div class=\"ng-scope\">Depuis le d\u00e9but de l\u2019hiver, certains \u00e9l\u00e8ves ont r\u00e9alis\u00e9s des nichoirs et un h\u00f4tel \u00e0 insectes.<\/div>\n<div class=\"ng-scope\">\u200b<\/div>\n<div class=\"ng-scope\">Les nichoirs finis ont \u00e9t\u00e9 install\u00e9s au niveau du verger alors que l\u2019h\u00f4tel \u00e0 insectes a \u00e9t\u00e9 mont\u00e9 \u00e0 proximit\u00e9 du potager en mandala, proche de l\u2019entr\u00e9e des \u00e9l\u00e8ves.<\/div>\n<div class=\"ng-scope\">\u200b<\/div>\n<div class=\"ng-scope\">le nichoir est encore en cours de remplissage, il a d\u00e9j\u00e0 pris quelques couleurs gr\u00e2ce \u00e0 la cr\u00e9ativit\u00e9 d\u2019\u00e9l\u00e8ves artistes! N\u2019h\u00e9sitez pas \u00e0 venir participer \u00e0 la finalisation de ce projet!<\/div>\n<div class=\"ng-scope\">\u200b<\/div>\n<div class=\"ng-scope\">\u200bVoici quelques photos:<\/div>\n<div><a href=\"http:\/\/clubscience.etab.ac-lille.fr\/files\/2020\/03\/823a3a95-11ff-4a94-9182-bfe12161afc3-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1147\" src=\"http:\/\/clubscience.etab.ac-lille.fr\/files\/2020\/03\/823a3a95-11ff-4a94-9182-bfe12161afc3-300x207.jpg\" alt=\"\" width=\"300\" height=\"207\" \/><\/a> <a href=\"http:\/\/clubscience.etab.ac-lille.fr\/files\/2020\/03\/80da62bb-18f9-42ac-9ae3-e2e21ec076aa-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1148\" src=\"http:\/\/clubscience.etab.ac-lille.fr\/files\/2020\/03\/80da62bb-18f9-42ac-9ae3-e2e21ec076aa-225x300.jpg\" alt=\"\" width=\"225\" height=\"300\" \/><\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Depuis le d\u00e9but de l\u2019hiver, certains \u00e9l\u00e8ves ont r\u00e9alis\u00e9s des nichoirs et un h\u00f4tel \u00e0 insectes. \u200b Les nichoirs finis ont \u00e9t\u00e9 install\u00e9s au niveau du verger alors que l\u2019h\u00f4tel \u00e0 insectes a \u00e9t\u00e9 mont\u00e9 \u00e0 proximit\u00e9 du potager en mandala, proche de l\u2019entr\u00e9e des \u00e9l\u00e8ves. \u200b le nichoir est encore en cours de remplissage, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-1146","post","type-post","status-publish","format-standard","hentry","category-articles"],"_links":{"self":[{"href":"https:\/\/clubnaturepasteur.fr\/index.php\/wp-json\/wp\/v2\/posts\/1146","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/clubnaturepasteur.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/clubnaturepasteur.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/clubnaturepasteur.fr\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/clubnaturepasteur.fr\/index.php\/wp-json\/wp\/v2\/comments?post=1146"}],"version-history":[{"count":0,"href":"https:\/\/clubnaturepasteur.fr\/index.php\/wp-json\/wp\/v2\/posts\/1146\/revisions"}],"wp:attachment":[{"href":"https:\/\/clubnaturepasteur.fr\/index.php\/wp-json\/wp\/v2\/media?parent=1146"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/clubnaturepasteur.fr\/index.php\/wp-json\/wp\/v2\/categories?post=1146"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/clubnaturepasteur.fr\/index.php\/wp-json\/wp\/v2\/tags?post=1146"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}