{"id":1267,"date":"2020-11-19T14:27:05","date_gmt":"2020-11-19T13:27:05","guid":{"rendered":"http:\/\/clubscience.etab.ac-lille.fr\/?p=1267"},"modified":"2020-11-19T14:27:05","modified_gmt":"2020-11-19T13:27:05","slug":"souvenez-vous-la-fauche-avant-la-toussaint","status":"publish","type":"post","link":"https:\/\/clubnaturepasteur.fr\/index.php\/2020\/11\/19\/souvenez-vous-la-fauche-avant-la-toussaint\/","title":{"rendered":"Souvenez-vous, la fauche avant la Toussaint"},"content":{"rendered":"\n<p>Bonjour \u00e0 tous,voici un petit retour sur un chantier tr\u00e8s important pour le maintien de la biodiversit\u00e9 au lyc\u00e9e ayant eu lieu au tout d\u00e9but des derni\u00e8res vacances\u00a0: la fauche des prairies\u00a0!C\u2019est aussi un chantier tr\u00e8s important car les prairies du lyc\u00e9e ne sont fauch\u00e9es qu\u2019une fois par an, tandis que les pelouses aux abords des b\u00e2timents sont tondues toutes les 3 \u00e0 4 semaines, ce qui illustre bien la gestion diff\u00e9renci\u00e9e mise en place au lyc\u00e9e depuis 6 ans d\u00e9j\u00e0.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"http:\/\/clubscience.etab.ac-lille.fr\/files\/2020\/11\/013a8f91-c9be-443d-b760-6745403e1fa6-1024x768.jpeg\" alt=\"\" class=\"wp-image-1268\" \/><\/figure>\n\n\n\n<p>Son principe\u00a0: une fois que le cycle de reproduction de la majorit\u00e9 des animaux et plantes est fini, les espaces sont fauch\u00e9s. Les d\u00e9chets de fauche \u00e9tant export\u00e9s dans les zones cultiv\u00e9es (afin de les enrichir en mati\u00e8re organique qui en se d\u00e9composant se transforme en mati\u00e8re min\u00e9rale utilisable par les v\u00e9g\u00e9taux), le sol des prairies s\u2019appauvrit au fil des ann\u00e9es, favorisant ainsi la biodiversit\u00e9. En effet, les plantes ayant pris le dessus durant l\u2019ann\u00e9e (comme les ronces ou les orties) \u00e9tant retir\u00e9es, cela laisse ainsi l\u2019occasion \u00e0 une plus grande diversit\u00e9 de plantes de s\u2019installer sur les lieux.<\/p>\n\n\n\n<div class=\"wp-block-group alignwide\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-group alignwide\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-group alignwide\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"http:\/\/clubscience.etab.ac-lille.fr\/files\/2020\/11\/be4352b0-bfdf-4fb4-8ccc-f218286bc0a6-1-1024x768.jpeg\" alt=\"\" class=\"wp-image-1272\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"http:\/\/clubscience.etab.ac-lille.fr\/files\/2020\/11\/a72bdcf4-6574-4cbb-b3ff-9080fb8a5870-1-1024x768.jpeg\" alt=\"\" class=\"wp-image-1273\" \/><\/figure>\n<\/div><\/div>\n<\/div><\/div>\n\n\n\n<p>Pour cela, nous avons \u00e9t\u00e9 accompagn\u00e9s de J\u00e9r\u00e9my Gruson de l\u2019association \u00ab&nbsp;Les Blongios&nbsp;\u00bb, sp\u00e9cialiste des chantiers nature, qui nous a fait part de ses connaissances en la mati\u00e8re et qui nous a apport\u00e9 son lot d\u2019outils \u00e0 utiliser \u00e0 bonne distance de ses voisins&nbsp;!Sous une m\u00e9t\u00e9o plut\u00f4t sympathique, ce sont donc les nombreux pr\u00e9sents qui se sont mis \u00e0 faucher, cisailler et couper avant m\u00eame que le caf\u00e9 ne soit pr\u00eat&nbsp;! Apr\u00e8s un bon petit-d\u00e9jeuner, les affaires reprennent et d\u00e9j\u00e0, vient le moment de ratisser, fourcher et amasser sur une b\u00e2che pour exporter le tout au potager&nbsp;! Ainsi continuera de se d\u00e9rouler une journ\u00e9e au cours de laquelle presque l\u2019ensemble des prairies sera fauch\u00e9&#8230;<\/p>\n<\/div><\/div>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"http:\/\/clubscience.etab.ac-lille.fr\/files\/2020\/11\/8e1a1833-77f9-4277-b826-c55f90322685-1-776x1024.jpeg\" alt=\"\" class=\"wp-image-1274\" \/><figcaption>Avant \/ Apr\u00e8s<\/figcaption><\/figure>\n\n\n\n<p><strong>Merci beaucoup \u00e0 tous les participants pour leur \u00e9nergie et leur bonne humeur\u00a0! \ud83d\ude09<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"http:\/\/clubscience.etab.ac-lille.fr\/files\/2020\/11\/e6815707-c910-4b2f-96e5-367c1a9b59c6-1024x768.jpeg\" alt=\"\" class=\"wp-image-1275\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Bonjour \u00e0 tous,voici un petit retour sur un chantier tr\u00e8s important pour le maintien de la biodiversit\u00e9 au lyc\u00e9e ayant eu lieu au tout d\u00e9but des derni\u00e8res vacances\u00a0: la fauche des prairies\u00a0!C\u2019est aussi un chantier tr\u00e8s important car les prairies du lyc\u00e9e ne sont fauch\u00e9es qu\u2019une fois par an, tandis que les pelouses aux abords [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1267","post","type-post","status-publish","format-standard","hentry","category-non-classe"],"_links":{"self":[{"href":"https:\/\/clubnaturepasteur.fr\/index.php\/wp-json\/wp\/v2\/posts\/1267","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/clubnaturepasteur.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/clubnaturepasteur.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/clubnaturepasteur.fr\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/clubnaturepasteur.fr\/index.php\/wp-json\/wp\/v2\/comments?post=1267"}],"version-history":[{"count":0,"href":"https:\/\/clubnaturepasteur.fr\/index.php\/wp-json\/wp\/v2\/posts\/1267\/revisions"}],"wp:attachment":[{"href":"https:\/\/clubnaturepasteur.fr\/index.php\/wp-json\/wp\/v2\/media?parent=1267"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/clubnaturepasteur.fr\/index.php\/wp-json\/wp\/v2\/categories?post=1267"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/clubnaturepasteur.fr\/index.php\/wp-json\/wp\/v2\/tags?post=1267"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}