{"id":1306,"date":"2021-01-03T13:25:14","date_gmt":"2021-01-03T12:25:14","guid":{"rendered":"http:\/\/clubscience.etab.ac-lille.fr\/?p=1306"},"modified":"2021-01-03T13:25:14","modified_gmt":"2021-01-03T12:25:14","slug":"2eme-rencontre-autour-du-projet-potager","status":"publish","type":"post","link":"https:\/\/clubnaturepasteur.fr\/index.php\/2021\/01\/03\/2eme-rencontre-autour-du-projet-potager\/","title":{"rendered":"2eme rencontre autour du projet potager"},"content":{"rendered":"\n<p>Beaucoup de monde ce samedi 12\/12&nbsp; pour cette rencontre autour du projet potager!\u200bApr\u00e8s une phase en salle pour pr\u00e9senter les 1er croquis et plan du potager, c&rsquo;est sur le terrain que la phase de r\u00e9flexion s&rsquo;est poursuivie avec l&rsquo;installation des cordeaux afin de mieux visualiser les futurs espaces.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/clubscience.etab.ac-lille.fr\/files\/2021\/01\/00d9f0e0-b61a-4cb7-8404-bba5bb676f75-1024x768.jpeg\" alt=\"\" class=\"wp-image-1307\" width=\"469\" height=\"352\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/clubscience.etab.ac-lille.fr\/files\/2021\/01\/65171954-4806-4e15-a499-dbd5b5aacebc-1024x683.jpeg\" alt=\"\" class=\"wp-image-1308\" width=\"585\" height=\"389\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/clubscience.etab.ac-lille.fr\/files\/2021\/01\/9881a8c2-2a4d-4faa-877d-67b3c66f7ca8-1024x683.jpeg\" alt=\"\" class=\"wp-image-1309\" width=\"493\" height=\"328\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/clubscience.etab.ac-lille.fr\/files\/2021\/01\/8a2057bc-e1d4-42da-8375-a2450ac8928c-1024x683.jpeg\" alt=\"\" class=\"wp-image-1310\" width=\"528\" height=\"350\" \/><figcaption>Le potager mandala a \u00e9t\u00e9 restructur\u00e9 et est en cours d&rsquo;agrandissement pour le connecter au futur potager.<\/figcaption><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/clubscience.etab.ac-lille.fr\/files\/2021\/01\/40bbe763-116a-4b67-ab34-3dd77c2c1a03-768x1024.jpeg\" alt=\"\" class=\"wp-image-1311\" width=\"383\" height=\"511\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/clubscience.etab.ac-lille.fr\/files\/2021\/01\/908bdb1f-83c9-4205-912b-c5961eb292d6-768x1024.jpeg\" alt=\"\" class=\"wp-image-1313\" width=\"428\" height=\"570\" \/><figcaption>Des semis de graines vari\u00e9es ont \u00e9t\u00e9 r\u00e9alis\u00e9s (pois, f\u00e8ves, moutarde, aneth, \u00e9pinards, salades&#8230;) En fonction de leur germination, elles nous indiqueront si le terrain leur est favorable. Nous gouterons une partie des jeunes pousses au prochain chantier.<\/figcaption><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/clubscience.etab.ac-lille.fr\/files\/2021\/01\/6c78a9af-3c9c-4d7b-be5d-db0584f98635-768x1024.jpeg\" alt=\"\" class=\"wp-image-1317\" width=\"429\" height=\"572\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/clubscience.etab.ac-lille.fr\/files\/2021\/01\/81c42edd-2ac8-4a16-a8c0-3a3b3c1e025c-768x1024.jpeg\" alt=\"\" class=\"wp-image-1314\" width=\"469\" height=\"625\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/clubscience.etab.ac-lille.fr\/files\/2021\/01\/ea77605d-d5c0-45ef-8a15-d19408615607-768x1024.jpeg\" alt=\"\" class=\"wp-image-1318\" width=\"431\" height=\"575\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/clubscience.etab.ac-lille.fr\/files\/2021\/01\/bc8ba083-eebb-4268-9059-2cf249fdf340-2-768x1024.jpeg\" alt=\"\" class=\"wp-image-1319\" width=\"430\" height=\"573\" \/><figcaption>Enfin, les futurs chemins ont \u00e9t\u00e9 mat\u00e9rialis\u00e9s avec de la farine<\/figcaption><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/clubscience.etab.ac-lille.fr\/files\/2021\/01\/3dbc5fc0-71f9-4320-ab9e-cf3c83adfc00-768x1024.jpeg\" alt=\"\" class=\"wp-image-1320\" width=\"428\" height=\"570\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/clubscience.etab.ac-lille.fr\/files\/2021\/01\/a4c1f217-8ab8-4880-a050-501a7e6037f7-949x1024.jpeg\" alt=\"\" class=\"wp-image-1321\" width=\"465\" height=\"502\" \/><figcaption>Vos avis et envies sont bienvenues afin de faire progresser le chantier.<\/figcaption><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/clubscience.etab.ac-lille.fr\/files\/2021\/01\/photo-1-1024x768.jpeg\" alt=\"\" class=\"wp-image-1347\" width=\"613\" height=\"460\" \/><figcaption><strong>Bravo a tous et merci pour votre investissement !<\/strong><\/figcaption><\/figure><\/div>\n\n\n\n<p>Prochain rendez-vous le samedi 16 Janvier! Vous \u00eates bienvenus!\u200b\u200b#clubsciencepasteurlille #clubsciencepasteur #chantiernature<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Beaucoup de monde ce samedi 12\/12&nbsp; pour cette rencontre autour du projet potager!\u200bApr\u00e8s une phase en salle pour pr\u00e9senter les 1er croquis et plan du potager, c&rsquo;est sur le terrain que la phase de r\u00e9flexion s&rsquo;est poursuivie avec l&rsquo;installation des cordeaux afin de mieux visualiser les futurs espaces. Prochain rendez-vous le samedi 16 Janvier! Vous [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-1306","post","type-post","status-publish","format-standard","hentry","category-articles"],"_links":{"self":[{"href":"https:\/\/clubnaturepasteur.fr\/index.php\/wp-json\/wp\/v2\/posts\/1306","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/clubnaturepasteur.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/clubnaturepasteur.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/clubnaturepasteur.fr\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/clubnaturepasteur.fr\/index.php\/wp-json\/wp\/v2\/comments?post=1306"}],"version-history":[{"count":0,"href":"https:\/\/clubnaturepasteur.fr\/index.php\/wp-json\/wp\/v2\/posts\/1306\/revisions"}],"wp:attachment":[{"href":"https:\/\/clubnaturepasteur.fr\/index.php\/wp-json\/wp\/v2\/media?parent=1306"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/clubnaturepasteur.fr\/index.php\/wp-json\/wp\/v2\/categories?post=1306"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/clubnaturepasteur.fr\/index.php\/wp-json\/wp\/v2\/tags?post=1306"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}