{"id":1370,"date":"2021-01-19T18:21:59","date_gmt":"2021-01-19T17:21:59","guid":{"rendered":"http:\/\/clubscience.etab.ac-lille.fr\/?p=1370"},"modified":"2021-01-19T18:21:59","modified_gmt":"2021-01-19T17:21:59","slug":"3eme-rencontre-autour-du-projet-potager","status":"publish","type":"post","link":"https:\/\/clubnaturepasteur.fr\/index.php\/2021\/01\/19\/3eme-rencontre-autour-du-projet-potager\/","title":{"rendered":"3\u00e8me rencontre autour du projet potager"},"content":{"rendered":"\n<p>Bonjour \u00e0 tous,\u200b\u200bCe samedi a eu lieu la 3eme rencontre autour du projet potager. Une quinzaine de participants, courageux, bravant le froid se sont retrouv\u00e9s.Une phase d&rsquo;\u00e9change en salle a permis de discuter de plusieurs points:<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img decoding=\"async\" src=\"http:\/\/clubscience.etab.ac-lille.fr\/files\/2021\/01\/70f698e9-9f28-4839-9564-260f1bda755e-1-1024x768.jpeg\" alt=\"\" class=\"wp-image-1371\" \/><\/figure><\/div>\n\n\n\n<p><\/p>\n\n\n\n<p>L\u00e9onard (le jardinier paysagiste qui nous accompagne) a propos\u00e9 quelques modifications des trac\u00e9s (avec notamment l&rsquo;installation d&rsquo;une zone de prairie fleurie au centre des parcelles cultiv\u00e9es rappelant que nous tentons de concilier culture en ville et biodiversit\u00e9).\u200bLes \u00e9changes ont aussi port\u00e9 sur la zone de rencontre, d&rsquo;\u00e9change, d&rsquo;expo&#8230; Elle serait constitu\u00e9e de 3 serres en forme d&rsquo;igloo et d&rsquo;un abris en pierre s\u00e9ches. L\u00e9onard souhaite utiliser des mat\u00e9riaux locaux et se renseigne sur la pierre de Pernes, un gr\u00e9 datant de 390millions d&rsquo;ann\u00e9e, roche peu connue dans la r\u00e9gion aux couleurs rouges et vertes. Un \u00e9chantillon est visible en salle 58.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"335\" height=\"333\" src=\"http:\/\/clubscience.etab.ac-lille.fr\/files\/2021\/01\/f522374e-2542-417c-8f12-ed6d4e19e931-2.jpeg\" alt=\"\" class=\"wp-image-1375\" srcset=\"https:\/\/clubnaturepasteur.fr\/wp-content\/uploads\/2021\/01\/f522374e-2542-417c-8f12-ed6d4e19e931-2.jpeg 335w, https:\/\/clubnaturepasteur.fr\/wp-content\/uploads\/2021\/01\/f522374e-2542-417c-8f12-ed6d4e19e931-2-300x298.jpeg 300w, https:\/\/clubnaturepasteur.fr\/wp-content\/uploads\/2021\/01\/f522374e-2542-417c-8f12-ed6d4e19e931-2-150x150.jpeg 150w\" sizes=\"auto, (max-width: 335px) 100vw, 335px\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/clubscience.etab.ac-lille.fr\/files\/2021\/01\/cfa8705d-9b87-4a0e-8067-60a7557c0989-3-1024x768.jpeg\" alt=\"\" class=\"wp-image-1376\" width=\"488\" height=\"365\" \/><\/figure><\/div>\n\n\n\n<p>L\u00e9onard envisage aussi de r\u00e9aliser des haies s\u00e8ches telles que celles que l&rsquo;on peut voir au Lac du H\u00e9ron. Abris \u00e0 faune, enrichissement du sol, structuration de l&rsquo;espace\u2026 Ces haies ont beaucoup d&rsquo;avantages.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img decoding=\"async\" src=\"http:\/\/clubscience.etab.ac-lille.fr\/files\/2021\/01\/a6e9e09c-3721-4979-a23b-2f167268fb88-1-1024x768.jpeg\" alt=\"\" class=\"wp-image-1377\" \/><\/figure><\/div>\n\n\n\n<p>Les \u00e9l\u00e8ves ont aussi d\u00e9cid\u00e9 de prendre la communication en main. Trop peu d&rsquo;\u00e9l\u00e8ves utilisent l&rsquo;ENT (peu de consultation des messages et des blogs \ud83d\ude41 sniff). Des afiiches seront bient\u00f4t expos\u00e9 afin d&rsquo;augmenter la visibilit\u00e9 du projet et attirer davantage d&rsquo;\u00e9l\u00e8ves.\u200bLe groupe s&rsquo;est ensuite divis\u00e9e en 2. L&rsquo;\u00e9quipe communication s&rsquo;est atel\u00e9e \u00e0 la r\u00e9alisation d&rsquo;affiches. Le reste des \u00e9l\u00e8ves est descendue sur le terrain afin de commencer \u00e0 tracer les all\u00e9es du futur jardin. Ce travail r\u00e9alis\u00e9 avec un bel enthousiasme s&rsquo;est termin\u00e9 sous la neige. Les parcelles commencent \u00e0 \u00eatre visibles. Reste \u00e0 poursuivre le travail afin que toutes les all\u00e9es soient de la m\u00eame largeur et praticables (en brouette notamment).<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/clubscience.etab.ac-lille.fr\/files\/2021\/01\/412034c8-9243-4098-8251-0468e28e1bfc-2-768x1024.jpeg\" alt=\"\" class=\"wp-image-1379\" width=\"394\" height=\"525\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/clubscience.etab.ac-lille.fr\/files\/2021\/01\/c85cce59-951f-4248-a601-ac95e156b697-1-768x1024.jpeg\" alt=\"\" class=\"wp-image-1380\" width=\"383\" height=\"510\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/clubscience.etab.ac-lille.fr\/files\/2021\/01\/87ef2ffc-bc31-48ef-9e1c-fc64eaa75c76-1-1024x768.jpeg\" alt=\"\" class=\"wp-image-1381\" width=\"543\" height=\"407\" \/><\/figure><\/div>\n\n\n\n<p class=\"has-text-align-center\">Les all\u00e9es \u00ab\u00a0courantes\u00a0\u00bb \u00e0 l&rsquo;arri\u00e8re des espaces cultiv\u00e9s reste \u00e0 r\u00e9aliser.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/clubscience.etab.ac-lille.fr\/files\/2021\/01\/e711defc-3b18-452a-b1ca-9b71e4475969-2-1024x715.jpeg\" alt=\"\" class=\"wp-image-1382\" width=\"511\" height=\"356\" \/><\/figure><\/div>\n\n\n\n<p class=\"has-text-align-center\">Nous commen\u00e7ons \u00e0 visualiser les parcelle\u2026<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img decoding=\"async\" src=\"http:\/\/clubscience.etab.ac-lille.fr\/files\/2021\/01\/2ee4a80a-501f-4826-82af-374e40685212-1.jpeg\" alt=\"\" class=\"wp-image-1383\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img decoding=\"async\" src=\"http:\/\/clubscience.etab.ac-lille.fr\/files\/2021\/01\/d33f19df-fa85-402e-8afe-13d531f6a053-2-1024x768.jpeg\" alt=\"\" class=\"wp-image-1384\" \/><\/figure><\/div>\n\n\n\n<p>Nous allons tenter de mettre en place une todo liste (une liste des t\u00e2ches \u00e0 r\u00e9aliser) afin que les plus motiv\u00e9s puissent y travailler quand ils le souhaitent.\u200bBravo et merci \u00e0 tous les participants,\u200b\u200b a tr\u00e8s vite, \u200b\u200bM. PIROT<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bonjour \u00e0 tous,\u200b\u200bCe samedi a eu lieu la 3eme rencontre autour du projet potager. Une quinzaine de participants, courageux, bravant le froid se sont retrouv\u00e9s.Une phase d&rsquo;\u00e9change en salle a permis de discuter de plusieurs points: L\u00e9onard (le jardinier paysagiste qui nous accompagne) a propos\u00e9 quelques modifications des trac\u00e9s (avec notamment l&rsquo;installation d&rsquo;une zone de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-1370","post","type-post","status-publish","format-standard","hentry","category-articles"],"_links":{"self":[{"href":"https:\/\/clubnaturepasteur.fr\/index.php\/wp-json\/wp\/v2\/posts\/1370","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/clubnaturepasteur.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/clubnaturepasteur.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/clubnaturepasteur.fr\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/clubnaturepasteur.fr\/index.php\/wp-json\/wp\/v2\/comments?post=1370"}],"version-history":[{"count":0,"href":"https:\/\/clubnaturepasteur.fr\/index.php\/wp-json\/wp\/v2\/posts\/1370\/revisions"}],"wp:attachment":[{"href":"https:\/\/clubnaturepasteur.fr\/index.php\/wp-json\/wp\/v2\/media?parent=1370"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/clubnaturepasteur.fr\/index.php\/wp-json\/wp\/v2\/categories?post=1370"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/clubnaturepasteur.fr\/index.php\/wp-json\/wp\/v2\/tags?post=1370"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}