{"id":2070,"date":"2024-02-03T17:15:51","date_gmt":"2024-02-03T16:15:51","guid":{"rendered":"http:\/\/clubscience.etab.ac-lille.fr\/?p=2056"},"modified":"2024-02-03T17:15:51","modified_gmt":"2024-02-03T16:15:51","slug":"lancement-des-premiers-semis","status":"publish","type":"post","link":"https:\/\/clubnaturepasteur.fr\/index.php\/2024\/02\/03\/lancement-des-premiers-semis\/","title":{"rendered":"Lancement des premiers semis !"},"content":{"rendered":"\n<p>Bonjour \u00e0 tous,<\/p>\n\n\n\n<p>\u200bDu monde encore ce matin pour la r\u00e9alisation des premiers semis de l&rsquo;a\u00a0\u00bbee en int\u00e9rieur (carottes h\u00e2tives, salades, pois mange tout et petits pis, \u00e9pinards, choux cabus et choux-fleurs et quelques fleurs&#8230;<\/p>\n\n\n\n<p>Nous esp\u00e9rons pouvoir planter tout cela d&rsquo;ici 1 mois dans notre serre ou sous voiles d&rsquo;hivernage histoire de gagner quelques semaines. Objectif: r\u00e9colter avec les \u00e9l\u00e8ves du Lyc\u00e9e h\u00f4telier international afin de pr\u00e9parer ensemble un repas avec nos l\u00e9gumes ! \ud83e\udd1e\ud83e\udd1e\ud83e\udd1e<\/p>\n\n\n\n<p>\u200bNous en avons profit\u00e9 pour commencer \u00e0 agrandir la toiture des cuves de r\u00e9cup\u00e9ration de d&rsquo;eau. Et pr\u00e9parer le potager sur buttes pour recevoir de nouvelles cultures\u2026\u00a0<\/p>\n\n\n\n<p>Du beau travail !&nbsp;<\/p>\n\n\n\n<p>\u200bBravo et merci \u00e0 tous les participants.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/clubscience.etab.ac-lille.fr\/files\/2024\/05\/2056_1.jpg\"><img decoding=\"async\" data-id=\"2057\" src=\"https:\/\/clubscience.etab.ac-lille.fr\/files\/2024\/05\/2056_1-1024x1024.jpg\" alt=\"\" class=\"wp-image-2057\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/clubscience.etab.ac-lille.fr\/files\/2024\/05\/2056_2.jpg\"><img decoding=\"async\" data-id=\"2060\" src=\"https:\/\/clubscience.etab.ac-lille.fr\/files\/2024\/05\/2056_2-1024x1024.jpg\" alt=\"\" class=\"wp-image-2060\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/clubscience.etab.ac-lille.fr\/files\/2024\/05\/2056_3.jpg\"><img decoding=\"async\" data-id=\"2061\" src=\"https:\/\/clubscience.etab.ac-lille.fr\/files\/2024\/05\/2056_3-1024x1024.jpg\" alt=\"\" class=\"wp-image-2061\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/clubscience.etab.ac-lille.fr\/files\/2024\/05\/2056_4.jpg\"><img decoding=\"async\" data-id=\"2059\" src=\"https:\/\/clubscience.etab.ac-lille.fr\/files\/2024\/05\/2056_4-1024x1024.jpg\" alt=\"\" class=\"wp-image-2059\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/clubscience.etab.ac-lille.fr\/files\/2024\/05\/2056_5.jpg\"><img decoding=\"async\" data-id=\"2058\" src=\"https:\/\/clubscience.etab.ac-lille.fr\/files\/2024\/05\/2056_5-1024x1024.jpg\" alt=\"\" class=\"wp-image-2058\" \/><\/a><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Bonjour \u00e0 tous, \u200bDu monde encore ce matin pour la r\u00e9alisation des premiers semis de l&rsquo;a\u00a0\u00bbee en int\u00e9rieur (carottes h\u00e2tives, salades, pois mange tout et petits pis, \u00e9pinards, choux cabus et choux-fleurs et quelques fleurs&#8230; Nous esp\u00e9rons pouvoir planter tout cela d&rsquo;ici 1 mois dans notre serre ou sous voiles d&rsquo;hivernage histoire de gagner quelques [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-2070","post","type-post","status-publish","format-standard","hentry","category-articles"],"_links":{"self":[{"href":"https:\/\/clubnaturepasteur.fr\/index.php\/wp-json\/wp\/v2\/posts\/2070","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/clubnaturepasteur.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/clubnaturepasteur.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/clubnaturepasteur.fr\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/clubnaturepasteur.fr\/index.php\/wp-json\/wp\/v2\/comments?post=2070"}],"version-history":[{"count":0,"href":"https:\/\/clubnaturepasteur.fr\/index.php\/wp-json\/wp\/v2\/posts\/2070\/revisions"}],"wp:attachment":[{"href":"https:\/\/clubnaturepasteur.fr\/index.php\/wp-json\/wp\/v2\/media?parent=2070"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/clubnaturepasteur.fr\/index.php\/wp-json\/wp\/v2\/categories?post=2070"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/clubnaturepasteur.fr\/index.php\/wp-json\/wp\/v2\/tags?post=2070"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}