{"id":565,"date":"2014-11-12T10:51:27","date_gmt":"2014-11-12T09:51:27","guid":{"rendered":"http:\/\/clubscience.etab.ac-lille.fr\/?p=565"},"modified":"2014-11-12T10:51:27","modified_gmt":"2014-11-12T09:51:27","slug":"rencontre-au-sommet","status":"publish","type":"post","link":"https:\/\/clubnaturepasteur.fr\/index.php\/2014\/11\/12\/rencontre-au-sommet\/","title":{"rendered":"Rencontre au sommet."},"content":{"rendered":"<p>Je sors, tu sors, il sort\u2026&#8230; Et si une simple sortie se transformait en\u00a0 reportage? Ok.<\/p>\n<p>Je m\u2019explique. Il nous est arriv\u00e9 d\u2019aller dans des concerts, ou au th\u00e9\u00e2tre, ou dans des vernissages, de ce fait, nous rencontrons les artistes. Mais avez-vous d\u00e9j\u00e0 questionn\u00e9 ces vedettes sur des th\u00e8mes n\u2019ayant pas forc\u00e9ment de rapport avec leurs professions\u00a0? Non\u00a0! Et bien c\u2019est ce qu\u2019ont fait nos \u00ab\u00a0anciens\u00a0\u00bb du Club.S qui lors d\u2019un concert de Didier Super nous ont rapport\u00e9 cette interview d\u00e9cal\u00e9e, forc\u00e9ment, \u00e0 l\u2019image du personnage.<\/p>\n<p>Merci \u00e0 Didier Super pour avoir ouvert les portes de sa loge.<\/p>\n<p>Merci \u00e0 Samuel de l\u2019avoir film\u00e9.<\/p>\n<p><a href=\"https:\/\/vimeo.com\/86242833\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-812 size-full\" src=\"http:\/\/clubscience.etab.ac-lille.fr\/files\/2016\/02\/Vim\u00e9oDidierFix.jpg\" alt=\"Vim\u00e9oDidierSuper\" width=\"960\" height=\"540\" \/><\/a><\/p>\n<p>Fr\u00e9d\u00e9ric W.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Je sors, tu sors, il sort\u2026&#8230; Et si une simple sortie se transformait en\u00a0 reportage? Ok. Je m\u2019explique. Il nous est arriv\u00e9 d\u2019aller dans des concerts, ou au th\u00e9\u00e2tre, ou dans des vernissages, de ce fait, nous rencontrons les artistes. Mais avez-vous d\u00e9j\u00e0 questionn\u00e9 ces vedettes sur des th\u00e8mes n\u2019ayant pas forc\u00e9ment de rapport avec [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-565","post","type-post","status-publish","format-standard","hentry","category-articles"],"_links":{"self":[{"href":"https:\/\/clubnaturepasteur.fr\/index.php\/wp-json\/wp\/v2\/posts\/565","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/clubnaturepasteur.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/clubnaturepasteur.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/clubnaturepasteur.fr\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/clubnaturepasteur.fr\/index.php\/wp-json\/wp\/v2\/comments?post=565"}],"version-history":[{"count":0,"href":"https:\/\/clubnaturepasteur.fr\/index.php\/wp-json\/wp\/v2\/posts\/565\/revisions"}],"wp:attachment":[{"href":"https:\/\/clubnaturepasteur.fr\/index.php\/wp-json\/wp\/v2\/media?parent=565"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/clubnaturepasteur.fr\/index.php\/wp-json\/wp\/v2\/categories?post=565"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/clubnaturepasteur.fr\/index.php\/wp-json\/wp\/v2\/tags?post=565"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}